{"id":2402,"date":"2024-04-02T09:37:23","date_gmt":"2024-04-02T09:37:23","guid":{"rendered":"https:\/\/learning.stay-erasmus.eu\/?post_type=case-studies&#038;p=2402"},"modified":"2024-06-06T09:49:42","modified_gmt":"2024-06-06T09:49:42","slug":"quinta-da-mata","status":"publish","type":"case-studies","link":"https:\/\/learning.stay-erasmus.eu\/it\/case-studies\/quinta-da-mata","title":{"rendered":"Quinta da Mata"},"content":{"rendered":"\n<p>Quinta da Mata \u00e8 una piccola azienda agrituristica a conduzione familiare con 3 appartamenti indipendenti (2 appartamenti con due camere e 1 appartamento con una camera) e la produzione di vino. In questa fattoria, i turisti godono di uno spazio unico con una magnifica vista sui vigneti e sulla valle, in mezzo alla natura, che consente privacy e isolamento, a pochi passi dal Parco Nazionale di Peneda-Ger\u00eas (unico e solo Parco Nazionale del Portogallo) e dalla citt\u00e0 di Ponte da Barca. La vicinanza al parco permette agli ospiti di esplorare le sue meraviglie naturali e di sperimentare la diversit\u00e0 della flora e della fauna che caratterizzano questa regione protetta. I turisti hanno la possibilit\u00e0 di partecipare alla vendemmia e ad altre attivit\u00e0 agricole.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Il viaggio di Quinta da Mata \u00e8 iniziato con la visione di unire agricoltura e turismo. Nonostante le difficolt\u00e0 iniziali, i proprietari hanno intrapreso una formazione in agricoltura e turismo, facendo leva sui fondi europei. Attualmente, l&#8217;attivit\u00e0 agrituristica ruota attorno a un vigneto di 4,5 ettari che produce vinho verde e contribuisce in modo significativo al reddito della famiglia.<\/p>\n","protected":false},"featured_media":1345,"template":"","class_list":["post-2402","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/learning.stay-erasmus.eu\/it\/wp-json\/wp\/v2\/case-studies\/2402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/learning.stay-erasmus.eu\/it\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/learning.stay-erasmus.eu\/it\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/learning.stay-erasmus.eu\/it\/wp-json\/wp\/v2\/media\/1345"}],"wp:attachment":[{"href":"https:\/\/learning.stay-erasmus.eu\/it\/wp-json\/wp\/v2\/media?parent=2402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}