{"id":2013,"date":"2024-04-03T06:21:06","date_gmt":"2024-04-03T06:21:06","guid":{"rendered":"https:\/\/learning.stay-erasmus.eu\/?post_type=case-studies&#038;p=2013"},"modified":"2024-04-30T08:00:56","modified_gmt":"2024-04-30T08:00:56","slug":"the-tominc-frelih-farm","status":"publish","type":"case-studies","link":"https:\/\/learning.stay-erasmus.eu\/it\/case-studies\/the-tominc-frelih-farm","title":{"rendered":"The Tominc &#8211; Frelih Farm"},"content":{"rendered":"\n<p>L&#8217;Agriturismo Tominc &#8211; Frelih si trova alla periferia del villaggio di Brezje, conosciuto come uno dei principali centri di pellegrinaggio della Slovenia. Oltre ai pellegrini, il villaggio \u00e8 visitato anche da ospiti stranieri che vogliono conoscere la Slovenia e vogliono trovarsi nelle immediate vicinanze di Bled e delle altre attrazioni turistiche dei dintorni. I visitatori pi\u00f9 assidui sono stranieri, che scelgono l&#8217;agriturismo non solo per la sua posizione ma anche per ci\u00f2 che offre. Sono attratti soprattutto dalla colazione, che consiste in ingredienti fatti in casa o locali. Pane, marmellate fatte in casa, verdura e frutta, carne, uova, succhi di frutta, latte, dolci freschi fatti in casa e molto altro ancora si trovano sulla tavola. Sono anche affascinati dalla fattoria: poche persone possono interagire con gli animali della fattoria in questo modo e vedere come funziona una fattoria da vicino. Questo \u00e8 particolarmente emozionante per i bambini. La fattoria ha iniziato a operare come agriturismo nel 2008. Tuttavia, il turismo si svolge in varie forme all&#8217;indirizzo della fattoria fin dal 1903.<\/p>\n","protected":false},"featured_media":1495,"template":"","class_list":["post-2013","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/learning.stay-erasmus.eu\/it\/wp-json\/wp\/v2\/case-studies\/2013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/learning.stay-erasmus.eu\/it\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/learning.stay-erasmus.eu\/it\/wp-json\/wp\/v2\/types\/case-studies"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/learning.stay-erasmus.eu\/it\/wp-json\/wp\/v2\/media\/1495"}],"wp:attachment":[{"href":"https:\/\/learning.stay-erasmus.eu\/it\/wp-json\/wp\/v2\/media?parent=2013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}