{"id":3651,"date":"2025-03-19T12:07:32","date_gmt":"2025-03-19T12:07:32","guid":{"rendered":"https:\/\/learning.stay-erasmus.eu\/training-modules\/introduccion-al-agroturismo"},"modified":"2025-05-21T08:10:24","modified_gmt":"2025-05-21T08:10:24","slug":"introduccion-al-agroturismo","status":"publish","type":"training-modules","link":"https:\/\/learning.stay-erasmus.eu\/es\/training-modules\/introduccion-al-agroturismo","title":{"rendered":"Introducci\u00f3n al agroturismo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3651\" class=\"elementor elementor-3651 elementor-2689\" data-elementor-post-type=\"training-modules\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0ee582 e-con-full e-flex e-con e-parent\" data-id=\"a0ee582\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div data-dce-title-color=\"#006034\" class=\"elementor-element elementor-element-66b6a35 elementor-widget elementor-widget-heading\" data-id=\"66b6a35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Objetivos de Aprendizaje<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ad90df elementor-widget elementor-widget-heading\" data-id=\"0ad90df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Conocimientos<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-502451d elementor-widget elementor-widget-text-editor\" data-id=\"502451d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El alumnado ser\u00e1 capaz de identificar las principales caracter\u00edsticas, contexto y evoluci\u00f3n del agroturismo y diferenciarlo de otros nichos de mercado tur\u00edstico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fa0858 elementor-widget elementor-widget-heading\" data-id=\"9fa0858\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Habilidades<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17832bb elementor-widget elementor-widget-text-editor\" data-id=\"17832bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El alumnado podr\u00e1 profundizar en los conocimientos proporcionados y adaptarlos a su contexto espec\u00edfico, identificando as\u00ed las pr\u00e1cticas m\u00e1s compatibles con el agroturismo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9761283 elementor-widget elementor-widget-heading\" data-id=\"9761283\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Competencias<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8f70a5 elementor-widget elementor-widget-text-editor\" data-id=\"a8f70a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El alumnado ser\u00e1 capaz de dedicarse al agroturismo o de reconducir una empresa tur\u00edstica existente para que se adapte mejor a los principios del agroturismo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#006034\" class=\"elementor-element elementor-element-e6f5cca elementor-widget elementor-widget-heading\" data-id=\"e6f5cca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Contenidos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d01e155 elementor-widget elementor-widget-n-accordion\" data-id=\"d01e155\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"unit1\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"unit1\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Fundamentos del turismo y el agroturismo <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"unit1\" class=\"elementor-element elementor-element-5eb8251 e-con-full e-flex e-con e-child\" data-id=\"5eb8251\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fca2c5 elementor-widget elementor-widget-heading\" data-id=\"2fca2c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Definici\u00f3n de agroturismo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26e9caa elementor-widget elementor-widget-text-editor\" data-id=\"26e9caa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agroturismo, agriturismo, agri-turismo, agroecoturismo, turismo en granjas, granja de vacaciones, turismo en granjas, etc. Distintas palabras para definir el mismo concepto, a veces con peque\u00f1as diferencias entre ellas. Cuando a\u00f1adimos t\u00e9rminos como gastroturismo, enoturismo, oleoturismo, ecoturismo, turismo verde o turismo rural, que a menudo se solapan, podemos comprender f\u00e1cilmente la confusi\u00f3n acerca de este nicho de mercado tur\u00edstico tanto en la literatura acad\u00e9mica especializada como en el m\u00e1rquetin tur\u00edstico.  <\/p><p>El trabajo conceptual en el campo del agroturismo comenz\u00f3 en la d\u00e9cada de 1980. Transcurridos unos cuarenta a\u00f1os, el concepto de turismo rural act\u00faa como paraguas para modalidades tur\u00edsticas que tienen un escenario com\u00fan (el entorno rural,[1] en contraposici\u00f3n a la ciudad), pero presentan caracter\u00edsticas diferentes tanto en t\u00e9rminos de oferta como de demanda tur\u00edstica, lo que da lugar a la existencia de varios segmentos tur\u00edsticos o nichos de mercado, como el ecoturismo, el agroturismo (y todos los t\u00e9rminos similares enumerados al principio), el gastroturismo, el enoturismo, el turismo ornitol\u00f3gico, los deportes de aventura, el camping y el glamping, etc., que a menudo se solapan en el mismo lugar; los l\u00edmites entre ellos son a veces difusos. <\/p><p>Dado que no existe una definici\u00f3n oficial de agroturismo a nivel mundial, este m\u00f3dulo comenzar\u00e1 estableciendo los principios fundamentales sobre el tema para llegar a una definici\u00f3n pr\u00e1ctica para los fines del proyecto STAY. Consideraremos el agroturismo como aquella modalidad (o nicho de mercado) de turismo rural que se desarrolla como complemento de renta a la producci\u00f3n agraria y en la que la principal motivaci\u00f3n de los turistas es la pr\u00e1ctica de actividades vinculadas a los oficios agr\u00edcolas y al estilo de vida agrario (este es el elemento diferenciador), junto con los propietarios de la explotaci\u00f3n. <\/p><p>Como ya se ha dicho, el elemento clave del agroturismo es la actividad agr\u00edcola y el propio modo de vida rural. As\u00ed, los agroturistas quieren sumergirse en el mundo rural, conocer a los agricultores y a sus familias, conocer de primera mano, e incluso participar, en algunas de las tareas del campo, como orde\u00f1ar una vaca o una cabra, dar de comer al ganado, recoger frutas o verduras del huerto, participar en el laboreo de la tierra, la cosecha de los cultivos, hornear pan o pasteles, hacer queso o mermelada, cocinar recetas tradicionales, etc., y degustar y comprar los productos de la granja (y de los vecinos). Por supuesto, pueden visitar los alrededores e incluso participar en otras actividades (visitas culturales, senderismo, equitaci\u00f3n, deportes de aventura, bienestar, observaci\u00f3n de aves, etc.), pero estas sirven como complemento, no como objetivo principal de las vacaciones. De lo contrario, se clasificar\u00eda como turismo rural y no como agroturismo. El alojamiento es un requisito fundamental para que una experiencia se considere tur\u00edstica; sin \u00e9l, nos referir\u00edamos a la recreaci\u00f3n (seg\u00fan la definici\u00f3n de turismo de ONU Turismo).    <\/p><div style=\"text-align: center;\">El concepto de turismo rural seg\u00fan ONU Turismo (UNWTO)<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ff0631 elementor-widget__width-initial dce_masking-none elementor-widget elementor-widget-image\" data-id=\"8ff0631\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"705\" height=\"526\" src=\"https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/04\/WP3_A2_TM_M1-01_ES.png\" class=\"attachment-medium_large size-medium_large wp-image-2728\" alt=\"\" srcset=\"https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/04\/WP3_A2_TM_M1-01_ES.png 705w, https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/04\/WP3_A2_TM_M1-01_ES-300x224.png 300w\" sizes=\"(max-width: 705px) 100vw, 705px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><b>Figura 1:<\/b> Source: Nulty, P. M. (2004). Keynote Presentation: Establishing the Principles for Sustainable Rural Tourism, Rural Tourism in Europe: Experiences. Development and Perspectives, WTO, 2  <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d61d71e elementor-widget elementor-widget-text-editor\" data-id=\"d61d71e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En resumen, el agroturismo es una forma de disfrutar de unas vacaciones diferentes, contribuyendo a mantener vivos los oficios tradicionales y la econom\u00eda rural. Pero, al mismo tiempo, incluye un claro componente educativo (se basa en el conocimiento del trabajo y la vida en el campo) y social (los turistas comparten conocimientos y experiencias con la poblaci\u00f3n local y participan en la cultura y las tradiciones del territorio que visitan). As\u00ed pues, este tipo de turismo lo suelen practicar personas que han crecido en las ciudades y no est\u00e1n muy familiarizadas con el trabajo en el campo, pero se sienten muy atra\u00eddas por \u00e9l, incluso como tiempo de ocio.  <\/p><p>En conclusi\u00f3n, el agroturismo es algo m\u00e1s que turismo rural; es una forma de turismo en la que la propia finca agr\u00edcola sirve de atracci\u00f3n principal. Los l\u00edmites difusos y el solapamiento con otras modalidades tur\u00edsticas son habituales y el significado del concepto muestra algunas diferencias entre territorios. As\u00ed, lo que se define legalmente como agroturismo en algunos lugares puede no considerarse como tal en un territorio diferente (\u00a1incluso en el mismo pa\u00eds!). Y, por \u00faltimo, llegamos a la comercializaci\u00f3n: un alojamiento situado en el campo con solo un peque\u00f1o zoo de mascotas para ni\u00f1os y un modesto huerto dista mucho del modelo de agroturismo que STAY pretende impulsar en el campo europeo.   <\/p><ul><li><span style=\"font-weight: 400;\">Hora de debatir: <a href=\"https:\/\/lc.cx\/Nic9BW\" target=\"_blank\" rel=\"noopener\">\u00bfes esto agroturismo \u00abde verdad\u00bb?<\/a><\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"unit1\" class=\"elementor-element elementor-element-2da8b36 e-flex e-con-boxed e-con e-child\" data-id=\"2da8b36\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d532f2 elementor-widget elementor-widget-heading\" data-id=\"1d532f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 es el agroturismo seg\u00fan STAY?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fb1bb0 elementor-widget elementor-widget-text-editor\" data-id=\"3fb1bb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>STAY pretende volver a lo b\u00e1sico:<\/p><p><strong>S<\/strong> es de \u00abstill\u201d, \u201cslow\u201d, \u201csustainable\u201d (tranquilo, lento, sostenible), porque as\u00ed es como queremos que se desarrolle la actividad, la forma en que los turistas disfrutan de su tiempo en el territorio rural. No pretendemos fomentar cualquier tipo de turismo, aunque se desarrolle en el medio rural, sino aquel que tiene la granja, el mundo rural y el patrimonio rural como principales factores de atracci\u00f3n para los usuarios. <\/p><p><strong>T<\/strong> de \u00abtourism\u201d (turismo), un tema clave del proyecto. En sentido estricto, no hay turismo sin alojamiento: los turistas no son solo visitantes. <\/p><p><strong>A<\/strong> de \u00abaround\u201d (alrededor), porque hablamos de turismo de proximidad, de disfrutar de la vida en la granja y visitar lugares cercanos. Y por \u00abagriculture\u00bb (agricultura), porque la finca es el otro tema clave: nuestros turistas quieren sumergirse en el mundo rural, conocer de primera mano y participar en algunas de las tareas del campo. Pueden visitar los alrededores e incluso participar en otras actividades, pero estas sirven como complemento y no como objetivo principal de las vacaciones.  <\/p><p><strong>Y<\/strong> es por \u00abyard\u201d (patio), que refuerza tanto las ideas de cercan\u00eda como de jard\u00edn (por tanto, de agricultura). Y tambi\u00e9n tiene que ver con \u00abyou\u201d (t\u00fa), es decir, con encontrar experiencias que permitan a los turistas conectar consigo mismos. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eac3de3 elementor-widget__width-initial dce_masking-none elementor-widget elementor-widget-image\" data-id=\"eac3de3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"511\" src=\"https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-02-768x511.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2739\" alt=\"\" srcset=\"https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-02-768x511.jpg 768w, https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-02-300x200.jpg 300w, https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-02-1024x681.jpg 1024w, https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-02.jpg 1040w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><b>Figura 2:<\/b> La observaci\u00f3n de aves puede ser una actividad complementaria al agroturismo<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9055b2 elementor-widget elementor-widget-heading\" data-id=\"e9055b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Historia del agroturismo\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3786c08 elementor-widget elementor-widget-text-editor\" data-id=\"3786c08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"font-weight: 400;\">En el contexto europeo, el agroturismo se remonta a principios del siglo XX: en el Tirol, los Alpes alemanes y Baviera (vinculado al monta\u00f1ismo y el alpinismo) y en Inglaterra (como bed &amp; breakfasts). Cuando el sector de la hosteler\u00eda estaba surgiendo y las actividades tur\u00edsticas eran a\u00fan un privilegio para unos pocos, los viajeros sol\u00edan alojarse en casas de campo, compartiendo tiempo y mesa con los anfitriones. <\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48ec39b elementor-widget__width-initial dce_masking-none elementor-widget elementor-widget-image\" data-id=\"48ec39b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-03-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2746\" alt=\"\" srcset=\"https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-03-768x512.jpg 768w, https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-03-300x200.jpg 300w, https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-03-1024x683.jpg 1024w, https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-03.jpg 1039w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><b>Figura 3:<\/b> Senderismo junto al glaciar Pasterze, en el Tirol austriaco<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63f92de elementor-widget elementor-widget-text-editor\" data-id=\"63f92de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Eso fue antes del auge mundial del llamado turismo de masas, sobre todo de sol y playa, en la d\u00e9cada de 1960. Despu\u00e9s, a partir de los a\u00f1os 60, el turismo agr\u00edcola\/rural (el concepto de agroturismo a\u00fan no hab\u00eda aparecido) se extendi\u00f3 a varios pa\u00edses, como B\u00e9lgica, Holanda, Luxemburgo, Francia, Espa\u00f1a e Italia. M\u00e1s tarde, en los a\u00f1os 80, muchos gobiernos adoptaron este modelo como soluci\u00f3n a la crisis de la agricultura familiar, sobre todo gracias a la financiaci\u00f3n europea para la agricultura y el desarrollo rural. En consecuencia, multitud de mas\u00edas, fincas, lagares, casas de aldea, molinos, etc., se acondicionaron como alojamientos rurales, buscando la diversificaci\u00f3n econ\u00f3mica, la complementariedad de rentas y una f\u00f3rmula de revalorizaci\u00f3n del patrimonio familiar rural. Muchas de las normativas regionales o nacionales m\u00e1s antiguas sobre agroturismo o turismo rural datan de los a\u00f1os 70 y 80, como en Italia, Portugal o las regiones espa\u00f1olas de Catalu\u00f1a y el Pa\u00eds Vasco.    <\/span><\/p><p><span style=\"font-weight: 400;\">El Tratado de Roma de 1957, por el que se constituy\u00f3 la Comunidad Econ\u00f3mica Europea, estableci\u00f3 varias medidas econ\u00f3micas y sociales, entre ellas la creaci\u00f3n de una Pol\u00edtica Agr\u00edcola Com\u00fan (PAC) con dos objetivos principales: garantizar un nivel de vida justo para la poblaci\u00f3n agr\u00edcola y asegurar el abastecimiento de los consumidores a precios bajos, y aumentar la producci\u00f3n agr\u00edcola y estabilizar los mercados. A partir de 1992, la PAC evolucion\u00f3 desde un enfoque productivista tradicional (proporcionar alimentos a los ciudadanos a precios asequibles y garantizar una renta decente y razonable a los agricultores) hacia un enfoque ruralista y multifuncional (sobre todo despu\u00e9s de la Agenda 2000). La producci\u00f3n agr\u00edcola sufri\u00f3 una revoluci\u00f3n: no solo hab\u00eda que producir alimentos, sino que hab\u00eda que hacerlo de forma respetuosa con el medio ambiente, con la PAC como garante. Por tanto, la agricultura multifuncional produce tanto bienes privados (alimentos, materias primas de origen agrario o agroturismo) como bienes p\u00fablicos, que se dividen en sociales (contribuci\u00f3n a la viabilidad de las zonas rurales desfavorecidas, protecci\u00f3n de los valores culturales y patrimoniales asociados al medio rural o protecci\u00f3n contra la despoblaci\u00f3n rural) y medioambientales (protecci\u00f3n de los valores paisaj\u00edsticos, fomento de la biodiversidad y reducci\u00f3n de los procesos de erosi\u00f3n del suelo).   <\/span><\/p><p><span style=\"font-weight: 400;\">Se han dedicado muchos millones de euros de la financiaci\u00f3n de la UE a impulsar iniciativas de turismo rural en el campo, muchas de las cuales se desarrollaron en granjas y fincas rurales activas (agroturismo). Se pueden identificar muchos ejemplos, como inversiones para restaurar edificios antiguos como alojamientos (granjas, establos, etc.), construir o renovar bodegas y queser\u00edas para acoger a los visitantes, etc. <\/span><\/p><p><span style=\"font-weight: 400;\">Toda esta financiaci\u00f3n ha procedido \u00fanicamente del sector de la agricultura (y el desarrollo rural) de la UE, pero se han dedicado m\u00e1s fondos a impulsar el agroturismo tanto directa como indirectamente en la UE a trav\u00e9s de otros medios, como los fondos EQUAL, Erasmus+ o Next Generation. Desde un punto de vista global, hay que destacar los esfuerzos realizados por los gobiernos nacionales, regionales y locales con cargo a sus propios presupuestos, as\u00ed como los de territorios no pertenecientes a la UE. <\/span><\/p><p><span style=\"font-weight: 400;\">Las inversiones p\u00fablicas y privadas en agroturismo a lo largo de los a\u00f1os han motivado un florecimiento del sector, aun cuando las cifras comparadas con el turismo de sol y playa est\u00e1n muy por debajo.<\/span><\/p><p><span style=\"font-weight: 400;\">El agroturismo no es hoy lo que era, ya que nuestra sociedad es muy diferente de la de principios del siglo XX. De alguna manera, tras medio siglo en el que el turismo ha pasado de ser una pr\u00e1ctica residual al alcance s\u00f3lo de unos pocos privilegiados a un fen\u00f3meno global de masas, motor econ\u00f3mico de muchos territorios, mientras el modo de vida rural tradicional est\u00e1 en peligro, y nuestra sociedad se digitaliza a un ritmo vertiginoso, nos encontramos ante un agroturismo 4.0 que mantiene muchas de las motivaciones y pr\u00e1cticas de los turistas pioneros, actualizadas con las necesidades y tendencias actuales. Adem\u00e1s, las tendencias m\u00e1s recientes del turismo rural son plenamente compatibles con el agroturismo m\u00e1s aut\u00e9ntico.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a74f561 elementor-widget elementor-widget-heading\" data-id=\"a74f561\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Panorama general del mercado del agroturismo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd4ccfa elementor-widget elementor-widget-text-editor\" data-id=\"fd4ccfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Solo se recogen datos sobre agroturismo en unos pocos destinos, ya que este nicho de mercado suele solaparse con otros, como el turismo rural o el ecoturismo (para m\u00e1s informaci\u00f3n, v\u00e9ase 1.1.1), y no suele haber un inter\u00e9s espec\u00edfico por parte de las autoridades tur\u00edsticas, agr\u00edcolas o de desarrollo rural en recoger los datos sobre agroturismo por separado.<\/span><\/p><p><span style=\"font-weight: 400;\">Dado que STAY es un proyecto financiado por Erasmus+, este m\u00f3dulo de formaci\u00f3n se centrar\u00e1 en ejemplos europeos, a pesar de incluir algunas referencias a otros pa\u00edses. <\/span><\/p><p><span style=\"font-weight: 400;\">El mejor con diferencia, al menos a nivel nacional, es el Observatorio Italiano del Agroturismo. La Ley Nacional Italiana de Agroturismo (Legge 20 febbraio 2006, n. 96, disciplina dell&#8217;agriturismo) prev\u00e9 su creaci\u00f3n. El objetivo del observatorio es facilitar el intercambio de experiencias a nivel nacional sobre el estado del agroturismo y complementarlo con datos sobre el tama\u00f1o del sector para elaborar un informe sobre su situaci\u00f3n actual. Cada a\u00f1o se elabora un estudio que sigue las tendencias del sector y presenta una instant\u00e1nea de la situaci\u00f3n en cifras y datos.   <\/span><\/p><p><span style=\"font-weight: 400;\">El Informe sobre Agroturismo y Multifuncionalidad, ahora en su s\u00e9ptima edici\u00f3n (2024), elaborado por el Instituto de Servicios para el Mercado Agroalimentario (ISMEA) en el marco de las actividades de la Red Rural Nacional, pretende ser una herramienta de orientaci\u00f3n, conocimiento y an\u00e1lisis del sector para apoyar las decisiones de instituciones, partes interesadas y agentes privados. Se analizan los principales indicadores y evidencias del mercado agroalimentario italiano (tanto de la oferta como de la demanda, utilizando datos ordenados por regiones o tipo de actividad). <\/span><\/p><p><span style=\"font-weight: 400;\">En algunos pa\u00edses, como en Espa\u00f1a, se recogen datos sobre el turismo rural a nivel nacional. El Instituto Nacional de Estad\u00edstica actualiza cada a\u00f1o la (<i>Encuesta de ocupaci\u00f3n en alojamientos tur\u00edsticos extrahoteleros &#8211; EOAT)<\/i>; el Ministerio de Agricultura elabora un Censo Agrario, aunque no se actualiza regularmente (la \u00faltima edici\u00f3n fue en 2020); y dos plataformas privadas de turismo rural (Escapada Rural y Clubrural) gestionan su propio observatorio con encuestas (casi) anuales. Lamentablemente, estas fuentes no distinguen entre establecimientos de agroturismo y otros alojamientos rurales (consulte los Informes Nacionales y el Informe de S\u00edntesis para m\u00e1s detalles en   <\/span><a href=\"https:\/\/stay-erasmus.eu\/es\/recursos\"><span style=\"font-weight: 400;\">stay-erasmus.eu\/es\/recursos<\/span><\/a><span style=\"font-weight: 400;\">)<\/span>.<\/p><p><span style=\"font-weight: 400;\">Por consiguiente, no es posible ofrecer una visi\u00f3n general del mercado mundial o europeo del agroturismo, sino solo sobre lugares concretos y, a veces, incluso a partir de investigaciones a medida (existen varios trabajos en la literatura especializada), ya que suelen faltar datos precisos.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb979b1 elementor-widget elementor-widget-heading\" data-id=\"bb979b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Buenas Pr\u00e1cticas en Agroturismo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e341a47 elementor-widget elementor-widget-text-editor\" data-id=\"e341a47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Como se ha descrito en secciones anteriores de esta unidad, no existe un enfoque \u00fanico del concepto de agroturismo y el contexto marca realmente la diferencia (por ejemplo, debido a un reconocimiento legal desigual de la actividad). As\u00ed pues, este m\u00f3dulo de formaci\u00f3n se centrar\u00e1 en las iniciativas que mejor se ajustan al concepto de agroturismo del proyecto STAY (ver secci\u00f3n 1.1.1) y, por tanto, destacar\u00e1 algunas buenas pr\u00e1cticas. <\/span><\/p><p><span style=\"font-weight: 400;\">El primer grupo se refiere a los estudios de casos desarrollados por los socios de STAY en el marco del proyecto. Se han identificado 18 empresas de agroturismo porque muestran historias de \u00e9xito en el emprendimiento en el campo europeo, dirigidas por agricultores. Proporcionan una imagen clara de las oportunidades y los retos para los empresarios, al esbozar los conocimientos, habilidades y capacidades necesarios para poner en marcha y gestionar empresas de agroturismo. Consulta los casos pr\u00e1cticos en la secci\u00f3n del <a href=\"https:\/\/stay-erasmus.eu\/es\/recursos\">sitio web del proyecto STAY<\/a> <span style=\"font-weight: 400;\">.<\/span>   <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6761e0a elementor-widget__width-initial dce_masking-none elementor-widget elementor-widget-image\" data-id=\"6761e0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-04.jpg\" class=\"attachment-large size-large wp-image-2753\" alt=\"\" srcset=\"https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-04.jpg 953w, https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-04-300x300.jpg 300w, https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-04-150x150.jpg 150w, https:\/\/learning.stay-erasmus.eu\/wp-content\/uploads\/2025\/03\/WP3_A2_TM_M1-04-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><b>Figura 4:<\/b> Algunos casos pr\u00e1cticos de STAY<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-122700a elementor-widget elementor-widget-text-editor\" data-id=\"122700a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>M\u00e1s all\u00e1 de nuestro proyecto, cabe destacar dos iniciativas francesas. La primera es <i>Accueil Paysan<\/i> (que significa \u00abacogida campesina\u00bb), una red de personas que ofrecen servicios de hoteler\u00eda en sus casas, en la granja y en el campo. Se cre\u00f3 en 1987. Los miembros de la red se agrupan en asociaciones locales. Juntos forman la <i>F\u00e9d\u00e9ration Nationale Accueil Paysan<\/i>, con sede en Grenoble (Francia). Actualmente cuenta con 800 integrantes en Francia y 230 m\u00e1s en 32 pa\u00edses. Los miembros participan en la gesti\u00f3n, animaci\u00f3n y construcci\u00f3n de la red a trav\u00e9s de comisiones o grupos de trabajo a nivel nacional y\/o local.      <\/p><p>La red <i>Accueil Paysan<\/i> existe para construir, defender y promover la agricultura campesina y un mundo rural diverso, solidario, ecol\u00f3gico y vivo. Sus miembros abren su espacio vital a visitantes y turistas y les dan la bienvenida para una estancia, una comida, un evento o una degustaci\u00f3n de productos, pero tambi\u00e9n para descubrir su profesi\u00f3n, su cultura y su territorio. Pertenecer a <i>Accueil Paysan<\/i> es m\u00e1s que ser miembro de una asociaci\u00f3n tur\u00edstica o de agricultores: es toda una filosof\u00eda de vida. Por eso <i>Accueil Paysan<\/i> fomenta un turismo abierto a todos, evitando el turismo de masas, y promueve la riqueza y la calidad de las relaciones humanas situando la convivencia y la autenticidad en el centro de sus pr\u00e1cticas. Adem\u00e1s, cuenta con el firme apoyo de la <i>Asociaci\u00f3n de Amigos de Accueil Paysan<\/i>, cuyo objetivo es fomentar y promover un modelo de turismo solidario. Las actividades de formaci\u00f3n para los socios, los intercambios entre pares y los comit\u00e9s de trabajo permiten a los miembros de la red mejorar sus competencias.     <\/p><p>El segundo ejemplo de Francia es <i>Bienvenue \u00e0 la ferme<\/i> (que significa \u00abbienvenidos a la granja\u00bb). Esta red, nacida en 1988, est\u00e1 coordinada por el Servicio de C\u00e1maras Agrarias de Francia y apoya a 10.000 productores locales a trav\u00e9s de asesores regionales en todo el pa\u00eds. Los miembros de <i>Bienvenue \u00e0 la Ferme<\/i> se comprometen a ofrecer productos agr\u00edcolas de alta calidad, a recibir a los clientes con un trato personalizado y profesional en un ambiente c\u00e1lido, y a actuar como embajadores de una agricultura sostenible y responsable. Se esfuerzan por mantener las tradiciones agr\u00edcolas profundamente arraigadas en la tierra, garantizando la conservaci\u00f3n de nuestro patrimonio agr\u00edcola com\u00fan. Sus granjas suelen formar parte de un entorno aut\u00e9ntico, rico en historia, tradiciones rurales y conocimientos en un entorno natural preservado.    <\/p><p>Por \u00faltimo, hay que destacar el esfuerzo realizado por muchos establecimientos de agroturismo para convertirse en un negocio m\u00e1s respetuoso con el medio ambiente. Por ejemplo, seg\u00fan una encuesta del Observatorio del Sal\u00f3n Nacional del Agroturismo y la Agricultura Multifuncional (AGRIeTOUR) en Italia durante 2024 (+3.000 empresas, 110 operadores tur\u00edsticos), el 76,8 % de los agroturismos consideran muy importante, casi un elemento discriminatorio en la elecci\u00f3n de los turistas, el ser percibidas como empresas ecol\u00f3gicas y preocupadas por la sostenibilidad. As\u00ed, el 73,6 % de los negocios encuestados afirman haber implantado soluciones tecnol\u00f3gicas de ahorro energ\u00e9tico. Entre ellas, el 29 % de los agroturismos est\u00e1n invirtiendo en tecnolog\u00edas y sistemas de dom\u00f3tica para controlar los dispositivos electr\u00f3nicos dentro de la instalaci\u00f3n, mientras el 23,2 % de los empresarios agrotur\u00edsticos est\u00e1n intentando enriquecer sus entornos con mobiliario basado en materiales sostenibles. Y m\u00e1s del 50 % de las empresas participantes en la encuesta est\u00e1n implantando (o estar\u00edan dispuestas) herramientas de inteligencia artificial.    <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e324abd elementor-widget elementor-widget-heading\" data-id=\"e324abd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Normativa sobre Agroturismo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-269a5be elementor-widget elementor-widget-text-editor\" data-id=\"269a5be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Al no existir una definici\u00f3n global del agroturismo, el marco jur\u00eddico de este tema es desigual y diverso. No solo a nivel nacional, sino incluso a nivel regional, donde se pueden identificar diferencias entre territorios seg\u00fan su propia regulaci\u00f3n. <\/span><\/p><p><span style=\"font-weight: 400;\">Se puede pensar que la raz\u00f3n de la falta de reconocimiento legal y de regulaci\u00f3n del agroturismo en cualquier territorio est\u00e1 relacionada con el escaso desarrollo de esta actividad, pero Austria, Francia o Alemania se encuentran entre los pa\u00edses pioneros en el desarrollo del turismo rural (agroturismo) y acogen a cientos de miles de agroturistas en total cada a\u00f1o y no han aprobado ninguna normativa sobre el tema. Por tanto, en cada territorio intervienen m\u00faltiples y diversos factores. El contexto es crucial.  <\/span><\/p><p><strong>Marco legal del agroturismo en algunos pa\u00edses<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2571151 eael-dt-th-align-center eael-table-align-center elementor-widget elementor-widget-eael-data-table\" data-id=\"2571151\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-data-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-data-table-wrap\" data-table_id=\"2571151\" id=\"eael-data-table-wrapper-2571151\" data-custom_responsive=\"false\">\n\t\t\t<table class=\"tablesorter eael-data-table center\" id=\"eael-data-table-2571151\">\n\t\t\t    <thead>\n\t\t\t        <tr class=\"table-header\">\n\t\t\t\t\t\t\t\t\t            <th class=\"\" id=\"\" colspan=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"data-table-header-text\">Sin normativa nacional<\/span><\/th>\n\t\t\t        \t\t\t\t            <th class=\"\" id=\"\" colspan=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"data-table-header-text\">Normativa nacional<\/span><\/th>\n\t\t\t        \t\t\t\t            <th class=\"\" id=\"\" colspan=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"data-table-header-text\">Regulaci\u00f3n a nivel regional (pero no nacional)<\/span><\/th>\n\t\t\t        \t\t\t\t        <\/tr>\n\t\t\t    <\/thead>\n\t\t\t  \t<tbody>\n\t\t\t\t\t\t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tAlemania, Austria, Francia, Pa\u00edses Bajos, Rep\u00fablica Checa y Suecia.\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tItalia, Panam\u00e1, Portugal, Eslovenia.\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tArgentina, Espa\u00f1a, Estados Unidos de Am\u00e9rica.\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t    <\/tbody>\n\t\t\t<\/table>\n\t\t<\/div>\n\t  \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a4a28b elementor-widget elementor-widget-text-editor\" data-id=\"4a4a28b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Cuando existe una normativa sobre agroturismo, suele depender de las autoridades agrarias, ya sea a nivel nacional o regional, pero a veces las competencias legales recaen en las autoridades tur\u00edsticas o incluso en ambas, como en las Islas Baleares (donde el agroturismo se regula tanto con una ley agraria como con un decreto tur\u00edstico).Argentina, Espa\u00f1a, Estados Unidos de Am\u00e9rica.<\/span><\/p><p><span style=\"font-weight: 400;\">El caso espa\u00f1ol es llamativo. El agroturismo se regul\u00f3 por primera vez en Catalu\u00f1a (1983) y el Pa\u00eds Vasco (1988), por decreto, y lo identificaron como un servicio de alojamiento rural prestado por agricultores, como complemento de renta, e integrado en una finca agr\u00edcola. En aquel momento, solo se contemplaba el agroturismo. Sin embargo, a partir de los a\u00f1os 90, el concepto evolucion\u00f3 hacia un turismo rural m\u00e1s gen\u00e9rico en el que se difumin\u00f3 el v\u00ednculo entre la actividad productiva agraria y el alojamiento de hu\u00e9spedes, y el agroturismo perdi\u00f3 su relevancia jur\u00eddica. Actualmente no existe ninguna normativa nacional, y todas las regiones espa\u00f1olas tienen normativas sobre turismo rural, pero solo diez hacen referencia expl\u00edcita al agroturismo. El enfoque del agroturismo var\u00eda seg\u00fan la regi\u00f3n. En algunas comunidades aut\u00f3nomas se define como un tipo espec\u00edfico de alojamiento rural, mientras que en otras se considera una categor\u00eda amplia que se aplica a todos los establecimientos de turismo rural. Adem\u00e1s, dos regiones incluso reconocen el agroturismo sin exigir una pernoctaci\u00f3n. Todas las regiones (menos una) identifican el agroturismo como un complemento de la renta agraria, pero solo una ha aprobado una normativa espec\u00edfica sobre agroturismo, mientras que las dem\u00e1s solo regulaban el turismo rural, e incluso dos de ellas cambiaron el \u00e1mbito de aplicaci\u00f3n del agroturismo al turismo rural hace algunos a\u00f1os (ver el informe sobre agroturismo en Espa\u00f1a).         <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"unit2\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"unit2\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Tendencias actuales y perspectivas de futuro del agroturismo <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"unit2\" class=\"elementor-element elementor-element-ae00b60 e-con-full e-flex e-con e-child\" data-id=\"ae00b60\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed0354f elementor-widget elementor-widget-heading\" data-id=\"ed0354f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Digitalizaci\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba4c981 elementor-widget elementor-widget-text-editor\" data-id=\"ba4c981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El turismo es uno de los sectores que m\u00e1s intensamente est\u00e1 incorporando la tecnolog\u00eda. Los agentes del turismo rural deben utilizar las tecnolog\u00edas para innovar y ofrecer nuevos productos, servicios y modelos de negocio a sus clientes, as\u00ed como para reinventarse, mejorando sus procesos y la calidad de sus productos. <\/span><\/p><p><span style=\"font-weight: 400;\">Tambi\u00e9n es, en parte, un legado de la pandemia. La mayor\u00eda de las industrias est\u00e1n experimentando los resultados de los avances tecnol\u00f3gicos y el creciente predominio del mundo digital, y cada vez dependemos m\u00e1s de internet y las redes sociales en el \u00e1mbito personal. Por ello, el sector tur\u00edstico est\u00e1 incorporando herramientas y procesos digitales y telem\u00e1ticos: big data, IA, internet de las cosas (IoT) y sensores, m\u00e1rquetin digital, redes sociales, servicios en l\u00ednea, automatizaci\u00f3n de procesos, dom\u00f3tica, etc. La adopci\u00f3n de tecnolog\u00eda en el turismo est\u00e1 relacionada sobre todo con el m\u00e1rquetin y la distribuci\u00f3n, y est\u00e1 menos orientada a la mejora de la productividad, mientras que las tecnolog\u00edas m\u00e1s avanzadas (big data, m\u00e1rquetin de relaciones con los clientes, etc.) siguen estando infrarrepresentadas. Y el sector del agroturismo, a pesar de la brecha digital que a menudo se experimenta en el campo, no es ajeno a esta tendencia.    <\/span><\/p><p><span style=\"font-weight: 400;\">Podemos mencionar dos ejemplos.<\/span><\/p><p><span style=\"font-weight: 400;\">El tema principal de la 22\u00aa Exposici\u00f3n Nacional de Agroturismo y Turismo Rural (AGRIeTOUR 2024), la principal feria sobre agricultura multifuncional y agroturismo celebrada en Italia, fue la inteligencia artificial en el mundo de la agricultura y el turismo rural. En consecuencia, la feria abord\u00f3 el reto de la inteligencia artificial en el sector (AGRI@INTELLIGENCE), tratando de conocer mejor c\u00f3mo mejorar la experiencia del viajero, personalizar los servicios prestados y mejorar la gesti\u00f3n de las hospitalidades. <\/span><\/p><p><span style=\"font-weight: 400;\">A principios de 2023 se present\u00f3 la Federaci\u00f3n Digital de Turismo (FEDITUR), una<\/span><span style=\"font-weight: 400;\"> alianza nacional de asociaciones espa\u00f1olas de turismo rural y de interior[1] cuyo objetivo es avanzar en la digitalizaci\u00f3n del sector. FEDITUR se cre\u00f3 para ayudar al sector a implantar las nuevas tecnolog\u00edas en la gesti\u00f3n de sus establecimientos con el fin de maximizar la rentabilidad y la eficiencia operativa, y prestar servicios tecnol\u00f3gicos avanzados de gesti\u00f3n. La digitalizaci\u00f3n, por tanto, ofrece una oportunidad para el trabajo colaborativo y en red.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8dc03b elementor-widget elementor-widget-heading\" data-id=\"f8dc03b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Experiencias y Personalizaci\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e2fdc5 elementor-widget elementor-widget-text-editor\" data-id=\"4e2fdc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">En los \u00faltimos 30 a\u00f1os, el mismo lema: \u00abLa demanda tur\u00edstica mundial est\u00e1 cambiando, surgen nuevas tendencias\u00bb. Los turistas son m\u00e1s experimentados y exigentes y, por tanto, buscan nuevos lugares, nuevas actividades, nuevos retos y nuevas experiencias. Los l\u00edmites del turismo se est\u00e1n ampliando. El turismo rural se ha identificado en todo el mundo como nueva tendencia tur\u00edstica durante d\u00e9cadas, mostrando cifras crecientes a\u00f1o tras a\u00f1o, pero a\u00fan muy lejos del turismo de sol y playa. La pandemia global generada por la COVID-19 motiv\u00f3 r\u00e1pidos cambios en la demanda tur\u00edstica: desplome de las llegadas internacionales, aceleraci\u00f3n del proceso de digitalizaci\u00f3n del sector (big data, inteligencia artificial, IoT y sensores, procesos telem\u00e1ticos), cambios en las prioridades de los turistas (m\u00e1s preocupados por la seguridad y la salud, demandando espacios abiertos para el distanciamiento social, la tranquilidad y la libertad), etc. As\u00ed, en esa primera etapa se deseaban experiencias menos masificadas, sostenibles y m\u00e1s cercanas, que garantizaran confianza y sensaci\u00f3n de control: turismo nacional familiar, viajes en coche y a destinos locales \u2500lo que beneficia a pueblos y zonas rurales\u2500, vuelta a la naturaleza, etc.     <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los turistas buscan cada vez m\u00e1s experiencias profundas y transformadoras, trato personalizado, microproductos tur\u00edsticos adaptados y a medida, etc. El II Congreso Internacional de Turismo de Interior de Andaluc\u00eda (2020) destac\u00f3 la importancia de la microsegmentaci\u00f3n: \u00abAsistimos a una nueva era, en la que la actividad tur\u00edstica se basa en micro nichos, de muy peque\u00f1o tama\u00f1o, pero tremendamente rentables. Saber identificar las necesidades y satisfacerlas se convierte en uno de los principales retos para empresas y destinos\u00bb. Diferenciaci\u00f3n, autenticidad e innovaci\u00f3n se identifican como las tres claves para el desarrollo de los microsegmentos en el turismo de interior.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con un consumidor experimentado y un tiempo libre a disposici\u00f3n de millones de personas, hemos pasado de la producci\u00f3n y el consumo en masa a un deseo de consumo personal e individual, lo que ha dado lugar a un producto tur\u00edstico a la carta. Turismo individualizado centrado en intereses especiales: agroturismo, turismo gastron\u00f3mico, ecoturismo, observaci\u00f3n de aves, astroturismo, etc. El turista de interior busca experiencias profundas, transformadoras y un trato personalizado. Un turista, un destino, una experiencia.   <\/span><\/p>\n<p><span style=\"font-weight: 400;\">La demanda empieza a decantarse por ofertas de \u00abexperiencias\u00bb, en las que se valoran los viajes activos y ricos en emociones, buscando una variedad de actividades que permitan el contacto con la historia, la cultura, el medio ambiente y las personas. Por tanto, la tendencia actual es buscar oportunidades de actividades con las que vivir experiencias agradables a trav\u00e9s del contacto directo y cercano con destinos naturales y rurales, especialmente para aquellos turistas m\u00e1s informados y con una visi\u00f3n consciente del impacto tur\u00edstico. Los turistas consideran en su decisi\u00f3n el encuentro con la poblaci\u00f3n local, las oportunidades de aprendizaje, as\u00ed como el disfrute del territorio.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este contexto, el agroturismo desempe\u00f1a un papel clave: \u00abEl consumidor desea entrar en contacto con la ruralidad y el campo, ya sea para encontrar sus ra\u00edces o simplemente para desconectar de la ciudad. Muchas generaciones de las sociedades urbanas actuales ya no mantienen sus v\u00ednculos familiares con el medio rural y, en consecuencia, se sienten atra\u00eddas por un espacio desconocido [&#8230;] Los productos tur\u00edsticos de los destinos de interior deben reflejar la identidad del territorio y deben centrarse en segmentos de la demanda comprometidos con la cultura local de los lugares a los que viajan [&#8230;] Los destinos de interior deben esforzarse por transformar los recursos existentes e incluso los productos tur\u00edsticos en emociones que hagan memorable la experiencia tur\u00edstica, de modo que los turistas est\u00e9n dispuestos a pasar m\u00e1s tiempo en el destino y gastar m\u00e1s dinero. En \u00faltima instancia, si los destinos no pueden emocionar a los turistas durante su visita, dif\u00edcilmente ser\u00e1n tenidos en cuenta por el cliente potencial\u00bb (Universidad de Ja\u00e9n, 2020).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este caso, aprender a orde\u00f1ar una vaca, esquilar una oveja, alimentar al ganado, hacer queso o pan, recoger fruta o participar en el laboreo de la tierra son algunas de las experiencias que pueden vivir los agroturistas para escapar de la vida urbana. O simplemente tener una agradable charla con el granjero y su familia. Incluso pueden incorporarse algunas actividades que no est\u00e1n tan directamente relacionadas con la vida en la finca, pero que son complementarias y compatibles, como las consideradas turismo naranja o creativo (por ejemplo, hacer artesan\u00eda), bienestar (en sentido amplio: ba\u00f1os de bosque, meditaci\u00f3n, yoga, mindfulness, masajes) u observaci\u00f3n de aves. Vivir la experiencia, de eso se trata. Actuar (por un tiempo) como agricultor, solo por diversi\u00f3n, solo para saber qu\u00e9 se siente. Agroturismo 4.0, acorde con los nuevos tiempos, pero sin perder la esencia ni el v\u00ednculo con lo agrario, con el factor decisivo en la elecci\u00f3n del destino de vacaciones: vivir la experiencia en la explotaci\u00f3n agr\u00edcola.     <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f11670a elementor-widget elementor-widget-heading\" data-id=\"f11670a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"> Integraci\u00f3n e Impacto en la Comunidad Local<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3399571 elementor-widget elementor-widget-text-editor\" data-id=\"3399571\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Con la creciente importancia de la multifuncionalidad y la sostenibilidad en el marco de la PAC, los agricultores no solo son considerados responsables de la producci\u00f3n de alimentos, sino tambi\u00e9n del mantenimiento del paisaje agrario y, por extensi\u00f3n, del mundo rural. Por tanto, en el campo convergen funciones productivas (agricultura y ganader\u00eda), recreativas (agroturismo y turismo rural) y est\u00e9ticas (paisaje agrario). <\/span><\/p><p><span style=\"font-weight: 400;\">Muchos habitantes de las ciudades buscan el contacto con la vida agraria y rural, como si se tratara de un enclave id\u00edlico, lo que implica superar nuevos retos, como la necesidad de consumir productos aut\u00e9nticos y de calidad y de volver a conectar con sus ra\u00edces, buscando nuevas tendencias de turismo no masificado. Estos turistas suelen consumir m\u00e1s productos locales y ecol\u00f3gicos, frecuentan restaurantes m\u00e1s t\u00edpicos y prefieren el agroturismo. No en vano, la producci\u00f3n agr\u00edcola del agroturismo suele ser m\u00e1s respetuosa con el medio ambiente: por ejemplo, en Italia, el 26,6 % de las explotaciones agrotur\u00edsticas han adoptado la producci\u00f3n ecol\u00f3gica (frente al   <a href=\"https:\/\/lc.cx\/VMmAYC\" target=\"_blank\" rel=\"noopener\">7,4 % de las dem\u00e1s explotaciones<\/a><\/span><span style=\"font-weight: 400;\">).<\/span><\/p><p><span style=\"font-weight: 400;\">El agroturismo, por sus caracter\u00edsticas, est\u00e1 profundamente arraigado en el territorio en el que se desarrolla y tiene implicaciones que van mucho m\u00e1s all\u00e1 de la propia actividad recreativa. Es inevitablemente turismo de proximidad, km. 0 (de la granja a la mesa, en este caso). Conocer, experimentar y disfrutar de la vida en la granja, en algunos casos casi como un miembro m\u00e1s de la familia (durante unos d\u00edas), es el principal motivo de las vacaciones. Por supuesto, podemos encontrar desde experiencias realmente inmersivas hasta otras ligeras, pero al final, es la vida en el campo lo que atrae el inter\u00e9s de los turistas, tanto en la propia finca agr\u00edcola como en su entorno inmediato: el pueblo, la ciudad, la regi\u00f3n.    <\/span><\/p><p><span style=\"font-weight: 400;\">As\u00ed pues, el agroturismo no solo repercute en la propia actividad agraria (los turistas demandan productos agroalimentarios para su abastecimiento, tanto de la explotaci\u00f3n como de los productores cercanos), lo que tiene implicaciones en t\u00e9rminos de renta y empleo (los turistas gastan dinero en dormir, comer, comprar productos agr\u00edcolas y ganaderos, y contratar actividades y servicios de ocio), algo fundamental en territorios de renta baja como muchas zonas agrarias, sino que tambi\u00e9n desempe\u00f1a un papel importante en el fortalecimiento de la identidad rural (hay personas dispuestas a pagar por conocer el modo de vida, la cultura, las tradiciones\u2026 locales; lo valoran y lo disfrutan) e incluso en la dotaci\u00f3n de servicios e infraestructuras en las comunidades rurales (una zona poco poblada que recibe flujos tur\u00edsticos y recreativos de cierta magnitud tiene necesidades adicionales que deben ser atendidas por las autoridades); lo valoran y lo disfrutan) e incluso en la provisi\u00f3n de servicios e infraestructuras en las comunidades rurales (una zona poco poblada que recibe flujos tur\u00edsticos y recreativos de cierta magnitud tiene necesidades adicionales que deben ser atendidas por las autoridades).<\/span><\/p><p><span style=\"font-weight: 400;\">Por tanto, no son solo los anfitriones, los que gestionan la finca, los que se benefician de acoger a los turistas, sino que toda la comunidad rural se beneficia indirectamente de alguna manera: restaurantes, bodegas, almazaras, tiendas de artesan\u00eda, museos y colecciones, empresas locales, etc. El agroturismo contribuye a conservar y revalorizar el patrimonio agr\u00edcola y rural, al tiempo que transfiere los conocimientos tradicionales para las generaciones futuras y mantiene el patrimonio edificado, las tradiciones y el patrimonio inmaterial ancestral. <\/span><\/p><p><span style=\"font-weight: 400;\">Y a\u00fan hay otros beneficios del agroturismo, esta vez para los visitantes. Las actividades de educaci\u00f3n e interpretaci\u00f3n medioambiental, como el compostaje, la jardiner\u00eda, la recolecci\u00f3n de hierbas arom\u00e1ticas o la elaboraci\u00f3n tradicional de alimentos o bebidas, ilustran la relaci\u00f3n entre turistas, agricultores y medio ambiente, que es un rasgo distintivo del agroturismo, y contribuyen a aumentar la conciencia medioambiental de los viajeros. Solo un ejemplo: en Italia, pa\u00eds europeo l\u00edder en el sector del agroturismo, los datos del censo muestran que en 2020 la proporci\u00f3n de superficie agr\u00edcola ecol\u00f3gica utilizada por las granjas de agroturismo (32,3 %) era el doble que la de otras granjas, y superior al objetivo (25 %) fijado por la estrategia <a href=\"https:\/\/lc.cx\/VMmAYC\" target=\"_blank\" rel=\"noopener\">\u00abDe la Granja a la Mesa\u00bb para la UE en 2023<\/a>  <\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"sec-divide\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"sec-divide\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Directrices informativas para educadores y asesores <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"sec-divide\" class=\"elementor-element elementor-element-081f1b4 e-con-full e-flex e-con e-child\" data-id=\"081f1b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ddfcb49 elementor-widget elementor-widget-text-editor\" data-id=\"ddfcb49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esta parte del m\u00f3dulo de formaci\u00f3n es una versi\u00f3n ampliada para que los educadores y asesores en agroturismo puedan encontrar informaci\u00f3n extra y profundizar en algunos contenidos. No todas las unidades se consideran con el mismo nivel de profundidad. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f46b45 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"2f46b45\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;stretch&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"49572677\" aria-label=\"Pesta\u00f1as. Abre elementos con Intro o Espacio, ci\u00e9rralos con Escape y navega con las fechas.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-495726771\" data-tab-title-id=\"e-n-tab-title-495726771\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-495726771\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tUnidad 1: Fundamentos del turismo y el agroturismo\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-495726772\" data-tab-title-id=\"e-n-tab-title-495726772\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-495726772\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tUnidad 2: Tendencias actuales y perspectivas de futuro del agroturismo\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div role=\"region tabpanel\" aria-labelledby=\"sec-divide e-n-tab-title-495726771\" id=\"e-n-tab-content-495726771\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-c3805b9 e-con-full e-flex e-con e-child\" data-id=\"c3805b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88127c5 elementor-widget elementor-widget-heading\" data-id=\"88127c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Definici\u00f3n de agroturismo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7307879 elementor-widget elementor-widget-text-editor\" data-id=\"7307879\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>En 2005 se celebr\u00f3 la <a href=\"https:\/\/lc.cx\/BwDFdL\">I Conferencia Nacional de Agroturismo en Espa\u00f1a<\/a>. Se acord\u00f3 una especie de definici\u00f3n, tal y como se recoge en el documento de conclusiones: \u00abpodemos hablar de agroturismo cuando el alojamiento en zonas rurales se realiza en el h\u00e1bitat de la poblaci\u00f3n rural, lo que facilita una relaci\u00f3n m\u00e1s estrecha con los habitantes y la vida en el campo. El objetivo principal es diversificar las actividades en la explotaci\u00f3n para mantener la poblaci\u00f3n y permitir el aumento de las rentas agrarias\u00bb. As\u00ed pues, los ingresos de las actividades tur\u00edsticas son un complemento de los procedentes de la agricultura. Y esas actividades deben estar vinculadas a una explotaci\u00f3n activa. La acogida por parte de los agricultores es la clave, por encima de las propias instalaciones. Es decir, la comunicaci\u00f3n y el respeto mutuo entre los anfitriones (que muestran su lugar, su profesi\u00f3n, sus productos locales, etc.) y los hu\u00e9spedes.     <\/li><li>El agroturismo ha ganado popularidad en los \u00faltimos 20 a\u00f1os y el volumen de literatura de investigaci\u00f3n en este campo crece continuamente. Su definici\u00f3n var\u00eda en todo el mundo (a veces incluso en el mismo pa\u00eds, como en Espa\u00f1a. Consultar el informe sobre agroturismo en Espa\u00f1a para m\u00e1s detalles) en funci\u00f3n de un conjunto de delimitaciones geoculturales y normativas. Por ello, el comit\u00e9 de Definici\u00f3n y Normas de la <a href=\"https:\/\/agritourism.eurac.edu\">Red Global de Agroturismo<\/a> (https:\/\/agritourism.eurac.edu) se dedica a formular una interpretaci\u00f3n global exhaustiva basada en valores amplios. Esa fue una de las actividades incluidas en el <a href=\"https:\/\/lc.cx\/b_Jkef\">II Congreso Mundial de Agroturismo<\/a> celebrado en mayo de 2024.   <\/li><li>Sourav Rauniyar et. al (2020)., <a href=\"https:\/\/doi.org\/10.1080\/02508281.2020.1753913\">Agritourism: structured literature review and bibliometric analysis<\/a>. Se analizaron los datos bibliogr\u00e1ficos de 459 investigaciones publicadas, obtenidas de las bases de datos Web of Science y Scopus para el periodo 1980-2019. Los resultados muestran que \u00abel agroturismo se conceptualiza en t\u00e9rminos generales como una amalgama de recursos, actividades y tradiciones agr\u00edcolas con fines l\u00fadicos y educativos, que se sirve como producto tur\u00edstico y, en \u00faltima instancia, aumenta los ingresos de los agricultores\u00bb. Esta teorizaci\u00f3n tan diversa del agroturismo por parte de los investigadores hace que una revisi\u00f3n bibliogr\u00e1fica sistem\u00e1tica del agroturismo sea una tarea notablemente necesaria y tambi\u00e9n conceptualmente desafiante\u00bb.  <\/li><li>Lista de referencias de la Red Global de Agroturismo, <a href=\"https:\/\/lc.cx\/WtcvEW\">lc.cx\/WtcvEW<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1c41be elementor-widget elementor-widget-heading\" data-id=\"f1c41be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Historia del agroturismo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d720321 elementor-widget elementor-widget-text-editor\" data-id=\"d720321\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Busby, G., &amp; Rendle, S. (2000). <a href=\"https:\/\/lc.cx\/WtcvEW\">The Transition from Tourism on Farms to Farm Tourism. Tourism Management <\/a> , 21, pp. 635-642,<\/li><li>Tradicionalmente, la Pol\u00edtica Agr\u00edcola Com\u00fan se financiaba a trav\u00e9s de un \u00fanico fondo, el Fondo Europeo de Orientaci\u00f3n y Garant\u00eda Agr\u00edcola (FEOGA), que fue sustituido en 2007 por el Fondo Europeo Agr\u00edcola de Garant\u00eda Agraria (FEAGA) y el Fondo Europeo Agrario de Desarrollo Rural (FEADER). Para el periodo 2021-2027, la PAC tiene asignados 387.000 millones de euros: 291.100 millones de euros del FEAGA y 95.500 millones de euros del FEADER. <\/li><li>M\u00e1s informaci\u00f3n sobre la <a href=\"https:\/\/lc.cx\/sewen6\">PAC<\/a><\/li><li>M\u00e1s informaci\u00f3n sobre los <a href=\"https:\/\/lc.cx\/0S9FQk\">fondos de la PAC<\/a><\/li><li><a href=\"https:\/\/lc.cx\/FY9Npn\" target=\"_blank\" rel=\"noopener\">Gu\u00eda de financiaci\u00f3n de la UE<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4da9a40 elementor-widget elementor-widget-heading\" data-id=\"4da9a40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Panorama general del mercado del agroturismo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9de182 elementor-widget elementor-widget-text-editor\" data-id=\"f9de182\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>A pesar de que rara vez se recogen datos espec\u00edficos sobre agroturismo, podemos encontrar algunos informes o investigaciones sobre el mercado agrotur\u00edstico, <a href=\"https:\/\/lc.cx\/gSHx3I\" target=\"_blank\" rel=\"noopener\">como este de una empresa privada<\/a>. Pero, \u00bfson realmente fiables cuando no se recogen datos oficiales y el agroturismo se define de forma diferente en cada territorio? <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2473c1d elementor-widget elementor-widget-heading\" data-id=\"2473c1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Buenas pr\u00e1cticas en agroturismo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b31d508 elementor-widget elementor-widget-text-editor\" data-id=\"b31d508\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><a href=\"https:\/\/lc.cx\/zXj_D7\">Fundaci\u00f3n Ecoagroturismo <\/a>(member of the Accueil Paysan network; in Spanish)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2883067 elementor-widget elementor-widget-heading\" data-id=\"2883067\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Normativa sobre agroturismo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-149bbd4 elementor-widget elementor-widget-text-editor\" data-id=\"149bbd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><a href=\"https:\/\/stay-erasmus.eu\/es\/recursos\" target=\"_blank\" rel=\"noopener\">Marco legal del turismo rural y el agroturismo en los pa\u00edses del consorcio STAY<\/a><\/li><li><a href=\"https:\/\/lc.cx\/Tq1qbA\" target=\"_blank\" rel=\"noopener\">La ley nacional de agroturismo de Panam\u00e1, la 1\u00aa de Am\u00e9rica<\/a><\/li><li><a href=\"https:\/\/lc.cx\/q_JgFC\" target=\"_blank\" rel=\"noopener\">Marco legal del turismo rural y el agroturismo en Argentina<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region tabpanel\" aria-labelledby=\"sec-divide e-n-tab-title-495726772\" id=\"e-n-tab-content-495726772\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-20bc45c e-con-full e-flex e-con e-child\" data-id=\"20bc45c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1dee74d elementor-widget elementor-widget-heading\" data-id=\"1dee74d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Experiencias y Personalizaci\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09ddce2 elementor-widget elementor-widget-text-editor\" data-id=\"09ddce2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Jurdana, D.S. (2024). <a href=\"https:\/\/jibi.aspur.rs\/archive\/v2\/n3\/8.php\">Evolution of trends affecting the tourism industry: business challenges in the future, Journal of Innovations in Business and Industry<\/a>, vol 2, number 3(8), pp. 193-204,<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2183\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2183\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Conclusiones <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2183\" class=\"elementor-element elementor-element-e3540bd e-con-full e-flex e-con e-child\" data-id=\"e3540bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3c8503 elementor-widget elementor-widget-text-editor\" data-id=\"a3c8503\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Definir el agroturismo no es tarea f\u00e1cil, sobre todo cuando se necesita una definici\u00f3n global. Hay varios elementos implicados que aportan muchos matices. Los contextos geogr\u00e1ficos, hist\u00f3ricos, jur\u00eddicos y culturales son fundamentales y, al final, diferenciales. Sin embargo, hay un elemento central claro: el estrecho v\u00ednculo entre el agroturismo, las explotaciones agrarias, el medio rural y el patrimonio rural.   <\/span><\/p><p><span style=\"font-weight: 400;\">Adem\u00e1s, la falta de datos espec\u00edficos y los solapamientos con otros nichos de mercado a\u00f1aden confusi\u00f3n.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2184\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2184\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Referencias \/ Enlaces <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2184\" class=\"elementor-element elementor-element-47a49f1 e-con-full e-flex e-con e-child\" data-id=\"47a49f1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a557994 elementor-widget elementor-widget-text-editor\" data-id=\"a557994\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.accueil-paysan.com\" target=\"_blank\" rel=\"noopener\">Accueil Paysan<\/a><\/p><p><a href=\"https:\/\/agrietour.it\" target=\"_blank\" rel=\"noopener\">AGRIeTOUR<\/a><\/p><p><a href=\"https:\/\/www.bienvenue-a-la-ferme.com\" target=\"_blank\" rel=\"noopener\">Bienvenue \u00e0 la ferme<\/a><\/p><p><a href=\"https:\/\/www.ismea.it\/flex\/cm\/pages\/ServeBLOB.php\/L\/IT\/IDPagina\/12900\" target=\"_blank\" rel=\"noopener\">Ismea. Agriturismo e multifunzionalit\u00e0. Scenario e propettive. Rapporto 2024   <\/a><\/p><p><a href=\"https:\/\/stay-erasmus.eu\/es\/recursos\" target=\"_blank\" rel=\"noopener\">National report of agrotourism in Spain<\/a><\/p><p><a href=\"https:\/\/lc.cx\/XlMkt0\" target=\"_blank\" rel=\"noopener\">University of Ja\u00e9n (2020). Conclusions of the 1st International Congress on Inland Tourism in Andalusia <\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2185\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2185\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cuestionario de autoevaluaci\u00f3n <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2185\" class=\"elementor-element elementor-element-9c1335d e-con-full e-flex e-con e-child\" data-id=\"9c1335d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37f447f elementor-widget elementor-widget-shortcode\" data-id=\"37f447f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><script>\n                            if (window.qmn_quiz_data === undefined) {\n                                    window.qmn_quiz_data = new Object();\n                            }\n                    <\/script><script>window.qmn_quiz_data[\"1\"] = {\"quiz_id\":\"1\",\"quiz_name\":\"Module 1 Quiz\",\"disable_answer\":0,\"ajax_show_correct\":0,\"progress_bar\":\"0\",\"contact_info_location\":0,\"qpages\":{\"1\":{\"id\":\"1\",\"quizID\":\"1\",\"pagekey\":\"WGXfvsRc\",\"hide_prevbtn\":\"0\"},\"2\":{\"id\":\"2\",\"quizID\":\"1\",\"pagekey\":\"vK3BhLep\",\"hide_prevbtn\":\"0\"},\"3\":{\"id\":\"3\",\"quizID\":\"1\",\"pagekey\":\"eqM5YAC2\",\"hide_prevbtn\":\"0\"}},\"skip_validation_time_expire\":0,\"timer_limit_val\":0,\"disable_scroll_next_previous_click\":0,\"disable_scroll_on_result\":0,\"disable_first_page\":0,\"enable_result_after_timer_end\":0,\"enable_quick_result_mc\":0,\"end_quiz_if_wrong\":0,\"form_disable_autofill\":0,\"disable_mathjax\":0,\"enable_quick_correct_answer_info\":\"1\",\"quick_result_correct_answer_text\":\"Correct! You have selected correct answer.\",\"quick_result_wrong_answer_text\":\"Wrong! You have selected wrong answer.\",\"quiz_processing_message\":\"\",\"quiz_limit_choice\":\"Limit of choice is reached.\",\"not_allow_after_expired_time\":0,\"scheduled_time_end\":false,\"prevent_reload\":0,\"limit_email_based_submission\":0,\"total_user_tries\":0,\"is_logged_in\":false,\"error_messages\":{\"email_error_text\":\"Not a valid e-mail address!\",\"number_error_text\":\"This field must be a number!\",\"incorrect_error_text\":\"The entered text is not correct!\",\"empty_error_text\":\"Please complete all required fields!\",\"url_error_text\":\"The entered URL is not valid!\",\"minlength_error_text\":\"Required atleast %minlength% characters.\",\"maxlength_error_text\":\"Maximum %maxlength% characters allowed.\",\"recaptcha_error_text\":\"ReCaptcha is missing\"},\"questions_settings\":[]}\n                    <\/script>\t\t<div class='qsm-quiz-container qsm-quiz-container-1 qmn_quiz_container mlw_qmn_quiz  quiz_theme_default random '>\n\t\t\t\t\t\t\t\t<form name=\"quizForm1\" id=\"quizForm1\" action=\"\/es\/wp-json\/wp\/v2\/training-modules\/3651\" method=\"POST\" class=\"qsm-quiz-form qmn_quiz_form mlw_quiz_form\" novalidate enctype=\"multipart\/form-data\">\n\t\t\t\t<input type=\"hidden\" name=\"qsm_hidden_questions\" id=\"qsm_hidden_questions\" value=\"\">\n\t\t\t\t<input type=\"hidden\" name=\"qsm_nonce\" id=\"qsm_nonce_1\" value=\"5d2ed2892c\">\n\t\t\t\t<input type=\"hidden\" name=\"qsm_unique_key\" id=\"qsm_unique_key_1\" value=\"6a0478704e988\">\n\t\t\t\t<div id=\"mlw_error_message\" class=\"qsm-error-message qmn_error_message_section\"><\/div>\n\t\t\t\t<span id=\"mlw_top_of_quiz\"><\/span>\n\t\t\t\t\t\t\t\t<section class=\"qsm-page qsm-question-page  qsm-page-1\"\n\t\t\t\t\t\tdata-pid=\"1\" data-qpid=\"1\" data-prevbtn=\"0\" style='display: none;'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class='quiz_section qsm-question-wrapper question-type-0 question-section-id-1 ' data-qid='1'>\n\t\t\t\t\t\t\t<div class='mlw_qmn_new_question'>El agroturismo es: <\/div>\n\t\t\t<div class='mlw_qmn_question  qsm_remove_bold' >\n\t\t<p><strong>Explicaci\u00f3n:<\/strong> Aunque no existe una definici\u00f3n universal del t\u00e9rmino agroturismo, est\u00e1 ampliamente aceptado que se trata de una modalidad o nicho de mercado del turismo rural,\nde la misma manera que el ecoturismo<\/p>\n\t<\/div>\n\t\t<fieldset>\n\t\t<legend><\/legend>\n\t<div class='qmn_radio_answers mlwRequiredRadio'>\n\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question1-1 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question1\" id=\"question1_1\" value=\"0\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question1_1\">\n\t\t\t\t\tUna marca de calidad creada por la Red Global de Agroturismo.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question1-2 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question1\" id=\"question1_2\" value=\"2\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question1_2\">\n\t\t\t\t\tUn nicho de mercado dentro del turismo rural.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question1-3 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question1\" id=\"question1_3\" value=\"1\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question1_3\">\n\t\t\t\t\tComo se llama en Francia al turismo en las granjas.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t \t\t\t<label style=\"display: none !important;\" for=\"question1_none\">Ninguna<\/label>\n\t\t\t<input type=\"radio\" style=\"display: none;\" name=\"question1\" id=\"question1_none\" checked=\"checked\" value=\"\" \/>\n\t\t\t\t<\/div>\n\t<\/fieldset>\n\t<input type=\"hidden\" name=\"answer_limit_keys_1\" value=\"\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class='quiz_section qsm-question-wrapper question-type-0 question-section-id-2 ' data-qid='2'>\n\t\t\t\t\t\t\t<div class='mlw_qmn_new_question'>Los datos oficiales sobre agroturismo: <\/div>\n\t\t\t<div class='mlw_qmn_question  qsm_remove_bold' >\n\t\t<p><strong>Explicaci\u00f3n:<\/strong> Solo se recopilan datos espec\u00edficos sobre agroturismo en unos pocos destinos, ya que este nicho de mercado suele solaparse con otros, como el turismo rural o el\necoturismo.<\/p>\n\t<\/div>\n\t\t<fieldset>\n\t\t<legend><\/legend>\n\t<div class='qmn_radio_answers mlwRequiredRadio'>\n\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question2-1 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question2\" id=\"question2_1\" value=\"1\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question2_1\">\n\t\t\t\t\tSe obtienen con facilidad, ya que existe un Observatorio Europeo del Agroturismo que\nrecopila datos peri\u00f3dicamente.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question2-2 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question2\" id=\"question2_2\" value=\"2\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question2_2\">\n\t\t\t\t\tSe recopilan de la misma forma que para el turismo rural.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question2-3 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question2\" id=\"question2_3\" value=\"0\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question2_3\">\n\t\t\t\t\tApenas est\u00e1n disponibles. Solo se recopilan en algunos territorios.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t \t\t\t<label style=\"display: none !important;\" for=\"question2_none\">Ninguna<\/label>\n\t\t\t<input type=\"radio\" style=\"display: none;\" name=\"question2\" id=\"question2_none\" checked=\"checked\" value=\"\" \/>\n\t\t\t\t<\/div>\n\t<\/fieldset>\n\t<input type=\"hidden\" name=\"answer_limit_keys_2\" value=\"\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class='quiz_section qsm-question-wrapper question-type-0 question-section-id-3 ' data-qid='3'>\n\t\t\t\t\t\t\t<div class='mlw_qmn_new_question'>El agroturismo est\u00e1 regulado: <\/div>\n\t\t\t<div class='mlw_qmn_question  qsm_remove_bold' >\n\t\t<p><strong>Explicaci\u00f3n:<\/strong> El marco jur\u00eddico del agroturismo es desigual: depende de cada territorio. Suele ser competencia de la autoridad agr\u00edcola, pero no siempre es as\u00ed. Por ejemplo, en Espa\u00f1a lo regulan sobre todo las autoridades tur\u00edsticas a nivel regional.<\/p>\n\t<\/div>\n\t\t<fieldset>\n\t\t<legend><\/legend>\n\t<div class='qmn_radio_answers mlwRequiredRadio'>\n\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question3-1 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question3\" id=\"question3_1\" value=\"1\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question3_1\">\n\t\t\t\t\tNo es necesaria ninguna regulaci\u00f3n.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question3-2 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question3\" id=\"question3_2\" value=\"2\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question3_2\">\n\t\t\t\t\t Depende del marco jur\u00eddico de cada territorio.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question3-3 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question3\" id=\"question3_3\" value=\"0\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question3_3\">\n\t\t\t\t\tPor la autoridad nacional de agricultura de cada pa\u00eds.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t \t\t\t<label style=\"display: none !important;\" for=\"question3_none\">Ninguna<\/label>\n\t\t\t<input type=\"radio\" style=\"display: none;\" name=\"question3\" id=\"question3_none\" checked=\"checked\" value=\"\" \/>\n\t\t\t\t<\/div>\n\t<\/fieldset>\n\t<input type=\"hidden\" name=\"answer_limit_keys_3\" value=\"\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/section>\n\t\t\t\t\t\t\t\t<section class=\"qsm-page qsm-question-page  qsm-page-2\"\n\t\t\t\t\t\tdata-pid=\"2\" data-qpid=\"2\" data-prevbtn=\"0\" style='display: none;'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class='quiz_section qsm-question-wrapper question-type-0 question-section-id-4 ' data-qid='4'>\n\t\t\t\t\t\t\t<div class='mlw_qmn_new_question'>Para dirigir una empresa de agroturismo <\/div>\n\t\t\t<div class='mlw_qmn_question  qsm_remove_bold' >\n\t\t<p><strong>Explicaci\u00f3n:<\/strong> El marco jur\u00eddico del agroturismo es desigual: depende de cada territorio. Por ejemplo, dentro de un mismo pa\u00eds el agroturismo puede seguir normas diferentes seg\u00fan la cu\u00e1l sea legislaci\u00f3n regional correspondiente.\n<\/p>\n\t<\/div>\n\t\t<fieldset>\n\t\t<legend><\/legend>\n\t<div class='qmn_radio_answers mlwRequiredRadio'>\n\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question4-1 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question4\" id=\"question4_1\" value=\"0\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question4_1\">\n\t\t\t\t\tEs obligatorio pasar un examen y pagar impuestos.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question4-2 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question4\" id=\"question4_2\" value=\"1\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question4_2\">\n\t\t\t\t\tEl propietario debe ser agricultor.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question4-3 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question4\" id=\"question4_3\" value=\"2\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question4_3\">\n\t\t\t\t\tCada territorio define sus requisitos legales.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t \t\t\t<label style=\"display: none !important;\" for=\"question4_none\">Ninguna<\/label>\n\t\t\t<input type=\"radio\" style=\"display: none;\" name=\"question4\" id=\"question4_none\" checked=\"checked\" value=\"\" \/>\n\t\t\t\t<\/div>\n\t<\/fieldset>\n\t<input type=\"hidden\" name=\"answer_limit_keys_4\" value=\"\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class='quiz_section qsm-question-wrapper question-type-0 question-section-id-5 ' data-qid='5'>\n\t\t\t\t\t\t\t<div class='mlw_qmn_new_question'>Elige la respuesta correcta: <\/div>\n\t\t\t<div class='mlw_qmn_question  qsm_remove_bold' >\n\t\t<p><strong>Explicaci\u00f3n:<\/strong> En Francia no existe una ley nacional sobre agroturismo. Alemania fue un pa\u00eds pionero en Europa en materia de casas de labranza que acog\u00edan viajeros. Todas las regiones de Espa\u00f1a han aprobado normativas sobre turismo rural, pero el agroturismo no siempre se tiene en cuenta en esas normativas regionales<\/p>\n\t<\/div>\n\t\t<fieldset>\n\t\t<legend><\/legend>\n\t<div class='qmn_radio_answers mlwRequiredRadio'>\n\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question5-1 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question5\" id=\"question5_1\" value=\"2\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question5_1\">\n\t\t\t\t\tEspa\u00f1a regula el agroturismo en todas las regiones, aunque no exista una ley nacional.\n\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question5-2 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question5\" id=\"question5_2\" value=\"1\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question5_2\">\n\t\t\t\t\tA pesar de la falta de regulaci\u00f3n nacional sobre agroturismo, Alemania fue uno de los primeros pa\u00edses europeos donde se desarrollaron estas pr\u00e1cticas.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question5-3 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question5\" id=\"question5_3\" value=\"0\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question5_3\">\n\t\t\t\t\tPodemos considerar a Francia como el mejor ejemplo de agroturismo en Europa por sus antecedentes jur\u00eddicos.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t \t\t\t<label style=\"display: none !important;\" for=\"question5_none\">Ninguna<\/label>\n\t\t\t<input type=\"radio\" style=\"display: none;\" name=\"question5\" id=\"question5_none\" checked=\"checked\" value=\"\" \/>\n\t\t\t\t<\/div>\n\t<\/fieldset>\n\t<input type=\"hidden\" name=\"answer_limit_keys_5\" value=\"\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class='quiz_section qsm-question-wrapper question-type-0 question-section-id-6 ' data-qid='6'>\n\t\t\t\t\t\t\t<div class='mlw_qmn_new_question'>Elige la respuesta correcta: <\/div>\n\t\t\t<div class='mlw_qmn_question  qsm_remove_bold' >\n\t\t<p><strong>Explicaci\u00f3n:<\/strong> Lo que diferencia al agroturismo de otros tipos de turismo rural es el hecho de que los turistas eligen un alojamiento que les permite experimentar de alg\u00fan modo la vida en la finca (aunque no se incorporen a las tareas agr\u00edcolas), y el emprendimiento tur\u00edstico es complementario a la actividad agr\u00edcola de los anfitriones. De lo contrario, deber\u00edamos considerar la actividad como turismo rural.<\/p>\n\t<\/div>\n\t\t<fieldset>\n\t\t<legend><\/legend>\n\t<div class='qmn_radio_answers mlwRequiredRadio'>\n\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question6-1 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question6\" id=\"question6_1\" value=\"0\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question6_1\">\n\t\t\t\t\tAl tratar de identificar el agroturismo, la vida en la explotaci\u00f3n agr\u00edcola es el concepto clave.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question6-2 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question6\" id=\"question6_2\" value=\"2\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question6_2\">\n\t\t\t\t\tEl agroturismo solo puede considerarse como tal cuando los hu\u00e9spedes colaboran en las actividades agr\u00edcolas.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question6-3 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question6\" id=\"question6_3\" value=\"1\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question6_3\">\n\t\t\t\t\tTurismo rural, agroturismo y turismo en la granja no son m\u00e1s que palabras diferentes para definir el mismo concepto.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t \t\t\t<label style=\"display: none !important;\" for=\"question6_none\">Ninguna<\/label>\n\t\t\t<input type=\"radio\" style=\"display: none;\" name=\"question6\" id=\"question6_none\" checked=\"checked\" value=\"\" \/>\n\t\t\t\t<\/div>\n\t<\/fieldset>\n\t<input type=\"hidden\" name=\"answer_limit_keys_6\" value=\"\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/section>\n\t\t\t\t\t\t\t\t<section class=\"qsm-page qsm-question-page  qsm-page-3\"\n\t\t\t\t\t\tdata-pid=\"3\" data-qpid=\"3\" data-prevbtn=\"0\" style='display: none;'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class='quiz_section qsm-question-wrapper question-type-0 question-section-id-7 ' data-qid='7'>\n\t\t\t\t\t\t\t<div class='mlw_qmn_new_question'>Elige la respuesta err\u00f3nea: <\/div>\n\t\t\t<div class='mlw_qmn_question  qsm_remove_bold' >\n\t\t<p><strong>Explicaci\u00f3n:<\/strong> Muchas zonas rurales tienen dificultades para conectarse a Internet, pero la digitalizaci\u00f3n es un proceso imparable en nuestra sociedad occidental. AGRI@TOUR 2024 fue un buen ejemplo.<\/p>\n\t<\/div>\n\t\t<fieldset>\n\t\t<legend><\/legend>\n\t<div class='qmn_radio_answers mlwRequiredRadio'>\n\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question7-1 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question7\" id=\"question7_1\" value=\"0\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question7_1\">\n\t\t\t\t\tLa digitalizaci\u00f3n est\u00e1 ganando importancia en el agroturismo, a pesar de las carencias de muchas zonas rurales.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question7-2 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question7\" id=\"question7_2\" value=\"1\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question7_2\">\n\t\t\t\t\tDigital o no, la vida en la finca agr\u00edcola sigue siendo el rasgo distintivo del agroturismo.\n\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question7-3 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question7\" id=\"question7_3\" value=\"2\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question7_3\">\n\t\t\t\t\tEl agroturismo es ajeno a la digitalizaci\u00f3n porque las zonas rurales suelen tener dificultades para conectarse a Internet.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t \t\t\t<label style=\"display: none !important;\" for=\"question7_none\">Ninguna<\/label>\n\t\t\t<input type=\"radio\" style=\"display: none;\" name=\"question7\" id=\"question7_none\" checked=\"checked\" value=\"\" \/>\n\t\t\t\t<\/div>\n\t<\/fieldset>\n\t<input type=\"hidden\" name=\"answer_limit_keys_7\" value=\"\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class='quiz_section qsm-question-wrapper question-type-0 question-section-id-8 ' data-qid='8'>\n\t\t\t\t\t\t\t<div class='mlw_qmn_new_question'>Elige la respuesta correcta: <\/div>\n\t\t\t<div class='mlw_qmn_question  qsm_remove_bold' >\n\t\t<p><strong>Explicaci\u00f3n:<\/strong> Los servicios y actividades tur\u00edsticas que prestan las explotaciones representan una renta complementaria de la agricultura y la ganader\u00eda, por lo que podemos considerarlas como explotaciones multifuncionales. El rendimiento de una explotaci\u00f3n no se ve comprometido por combinarla con otras actividades productivas si se destinan los recursos necesarios para desarrollar ambas con plenas garant\u00edas. Y una explotaci\u00f3n grande no implica necesariamente un desapego por parte de los anfitriones: intervienen otros factores.<\/p>\n\t<\/div>\n\t\t<fieldset>\n\t\t<legend><\/legend>\n\t<div class='qmn_radio_answers mlwRequiredRadio'>\n\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question8-1 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question8\" id=\"question8_1\" value=\"1\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question8_1\">\n\t\t\t\t\tLas explotaciones agr\u00edcolas que se dedican al agroturismo son menos eficientes que otras, ya que no pueden centrarse \u00fanicamente en la producci\u00f3n agr\u00edcola.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question8-2 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question8\" id=\"question8_2\" value=\"0\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question8_2\">\n\t\t\t\t\tEl agroturismo es un ejemplo de agricultura multifuncional.\n\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"qmn_mc_answer_wrap  mrq_checkbox_class\" id=\"question8-3 \">\n\t\t\t\t\t\t\t\t\t\t\t<input type='radio' class='qmn_quiz_radio qmn-multiple-choice-input ' name=\"question8\" id=\"question8_3\" value=\"2\" \/>\n\t\t\t\t\t<label class=\"qsm-input-label\" for=\"question8_3\">\n\t\t\t\t\tLas granjas enormes no son apropiadas para desarrollar actividades de agroturismo, ya que la sensaci\u00f3n de cercan\u00eda a los anfitriones se difumina f\u00e1cilmente.\t\t\t\t\t<\/label>\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t\t \t\t\t<label style=\"display: none !important;\" for=\"question8_none\">Ninguna<\/label>\n\t\t\t<input type=\"radio\" style=\"display: none;\" name=\"question8\" id=\"question8_none\" checked=\"checked\" value=\"\" \/>\n\t\t\t\t<\/div>\n\t<\/fieldset>\n\t<input type=\"hidden\" name=\"answer_limit_keys_8\" value=\"\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/section>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"qmn_question_list\" value=\"1Q2Q3Q4Q5Q6Q7Q8Q\" \/>\n\t\t\t\t\t\t\t<div id=\"mlw_error_message_bottom\" class=\"qsm-error-message qmn_error_message_section\"><\/div>\n\t\t\t\t\t<input type=\"hidden\" name=\"qmn_all_questions_count\" id=\"qmn_all_questions_count\" value=\"8\" \/>\n\t\t\t\t\t<input type=\"hidden\" name=\"total_questions\" id=\"total_questions\" value=\"8\" \/>\n\t\t\t\t\t<input type=\"hidden\" name=\"timer\" id=\"timer\" value=\"0\" \/>\n\t\t\t\t\t<input type=\"hidden\" name=\"timer_ms\" id=\"timer_ms\" value=\"0\"\/>\n\t\t\t\t\t<input type=\"hidden\" class=\"qmn_quiz_id\" name=\"qmn_quiz_id\" id=\"qmn_quiz_id\" value=\"1\" \/>\n\t\t\t\t\t<input type='hidden' name='complete_quiz' value='confirmation' \/>\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"quiz_answer_random_ids\" id=\"quiz_answer_random_ids_1\" value=\"a:8:{i:1;a:3:{i:0;i:0;i:1;i:2;i:2;i:1;}i:2;a:3:{i:0;i:1;i:1;i:2;i:2;i:0;}i:3;a:3:{i:0;i:1;i:1;i:2;i:2;i:0;}i:4;a:3:{i:0;i:0;i:1;i:1;i:2;i:2;}i:5;a:3:{i:0;i:2;i:1;i:1;i:2;i:0;}i:6;a:3:{i:0;i:0;i:1;i:2;i:2;i:1;}i:7;a:3:{i:0;i:0;i:1;i:1;i:2;i:2;}i:8;a:3:{i:0;i:1;i:1;i:0;i:2;i:2;}}\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t<div style=\"display: none;\" class=\"qsm-popup qsm-popup-slide\" id=\"modal-4\" aria-hidden=\"false\"><div class=\"qsm-popup__overlay\" tabindex=\"-1\" data-micromodal-close=\"\"><div class=\"qsm-popup__container qmn_quiz_container\" role=\"dialog\" aria-modal=\"true\"><div class=\"qsm-popup__content\"><img decoding=\"async\" src=\"https:\/\/learning.stay-erasmus.eu\/wp-content\/plugins\/quiz-master-next\/assets\/clock.png\" alt=\"clock.png\"\/><p class=\"qsm-time-up-text\"> Time's up<\/p><\/div><footer class=\"qsm-popup__footer\"><button class=\"qsm-popup-secondary-button qmn_btn\" data-micromodal-close=\"\" aria-label=\"Close this dialog window\" onclick=\"location.reload();\">Cancelar<\/button><\/footer><\/div><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-3651","training-modules","type-training-modules","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/learning.stay-erasmus.eu\/es\/wp-json\/wp\/v2\/training-modules\/3651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/learning.stay-erasmus.eu\/es\/wp-json\/wp\/v2\/training-modules"}],"about":[{"href":"https:\/\/learning.stay-erasmus.eu\/es\/wp-json\/wp\/v2\/types\/training-modules"}],"version-history":[{"count":36,"href":"https:\/\/learning.stay-erasmus.eu\/es\/wp-json\/wp\/v2\/training-modules\/3651\/revisions"}],"predecessor-version":[{"id":4632,"href":"https:\/\/learning.stay-erasmus.eu\/es\/wp-json\/wp\/v2\/training-modules\/3651\/revisions\/4632"}],"wp:attachment":[{"href":"https:\/\/learning.stay-erasmus.eu\/es\/wp-json\/wp\/v2\/media?parent=3651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}